{"id":1577,"date":"2020-12-04T08:08:28","date_gmt":"2020-12-04T08:08:28","guid":{"rendered":"https:\/\/icedusolutions.com\/noticias\/?p=1577"},"modified":"2021-05-30T17:15:01","modified_gmt":"2021-05-30T17:15:01","slug":"vocabulario-navidad-ingles","status":"publish","type":"post","link":"https:\/\/icedusolutions.com\/noticias\/vocabulario-navidad-ingles\/","title":{"rendered":"Vocabulario de navidad en ingl\u00e9s"},"content":{"rendered":"<div class=\"\" data-block=\"true\" data-editor=\"aon60\" data-offset-key=\"aqmlu-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"aqmlu-0-0\">\n<div class=\"\" data-block=\"true\" data-editor=\"aon60\" data-offset-key=\"aqmlu-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"aqmlu-0-0\"><span data-offset-key=\"aqmlu-0-0\">Like Christmas came early!!! ?<\/span><\/div>\n<div data-offset-key=\"aqmlu-0-0\">\u00a0<\/div>\n<\/div>\n<div data-offset-key=\"aqmlu-0-0\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1850 aligncenter\" src=\"https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/Christmas-tree-bro-1-300x300.png\" alt=\"Christmas vocabulary vocabulario ingl\u00e9s\" width=\"300\" height=\"300\" \/><\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"aon60\" data-offset-key=\"afhll-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"afhll-0-0\"><span data-offset-key=\"afhll-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"aon60\" data-offset-key=\"c6qb4-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"c6qb4-0-0\"><span data-offset-key=\"c6qb4-0-0\">Las luces de navidad ya est\u00e1n encendidas en las calles y muchas personas deciden adornar sus casas en este puente de diciembre para empezar a celebrar esta navidad at\u00edpica.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"aon60\" data-offset-key=\"84fhu-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"84fhu-0-0\"><span data-offset-key=\"84fhu-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"aon60\" data-offset-key=\"dnb03-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"dnb03-0-0\"><span data-offset-key=\"dnb03-0-0\">Por eso hoy os traemos como reto para este puente algunas de las palabras que m\u00e1s se utilizar\u00e1n en ingl\u00e9s en estas fechas ??<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><span lang=\"es\" tabindex=\"0\">A continuaci\u00f3n os dejamos un reto en ingl\u00e9s para estudiar 10 palabras cada d\u00eda del puente de viernes a martes \u00bfLo aceptas?<\/span><\/p>\n<p><span lang=\"es\" tabindex=\"0\">Come on, you can do it !!\u00a0<span class=\"_5mfr\"><span class=\"_6qdm\">?<\/span><\/span><span class=\"_5mfr\"><span class=\"_6qdm\">?<\/span><\/span><span class=\"_5mfr\"><span class=\"_6qdm\">?<\/span><\/span><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1847 size-full aligncenter\" src=\"https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/vocabulario-navidad-ingles.png\" alt=\"vocabulario navide\u00f1o ingles espa\u00f1ol\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/vocabulario-navidad-ingles.png 1920w, https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/vocabulario-navidad-ingles-1024x576.png 1024w, https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/vocabulario-navidad-ingles-768x432.png 768w, https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/vocabulario-navidad-ingles-1536x864.png 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p><span lang=\"es\" tabindex=\"0\">* EN PDF |\u00a0<a href=\"http:\/\/icedusolutions.com\/documentos\/vocabulario-navidad-ingles.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/icedusolutions.com\/documentos\/vocabulario-navidad-ingles.pdf<\/a><\/span><\/p>\n<p>\u00a0<\/p>\n<h2>Vocabulario de navidad en ingl\u00e9s<\/h2>\n<p>Veamos un poco de vocabulario en ingl\u00e9s relacionado con la Navidad por categor\u00edas:<\/p>\n<h3 class=\"heading\" style=\"text-align: center;\">Comida de navidad en ingl\u00e9s<\/h3>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1581 size-full\" title=\"comida de navidad en ingl\u00e9s\" src=\"https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2019\/12\/comida-de-navidad-en-ingles.jpg\" alt=\"\" width=\"626\" height=\"271\" \/><\/em><\/p>\n<ul>\n<li><em>Candy cane<\/em>\u00a0&#8211; Bast\u00f3n de caramelo<\/li>\n<li><em>Cava<\/em>\u00a0&#8211; Cava<\/li>\n<li><em>Champagne<\/em>\u00a0&#8211; Champa\u00f1a<\/li>\n<li><em>Chestnuts<\/em>\u00a0&#8211; Casta\u00f1as<\/li>\n<li><em>Christmas dinner<\/em>\u00a0&#8211; Cena de Navidad<\/li>\n<li><em>Christmas basket<\/em>\u00a0&#8211; Cesta de Navidad<\/li>\n<li>Christmas Pudding &#8211; Pastel de ciruelas con salsa de ron<\/li>\n<li>Cranberry sauce &#8211; Salsa de ar\u00e1ndonos<\/li>\n<li><em>Cookie<\/em>\u00a0&#8211; Galleta<\/li>\n<li><em>Eggnog\u00a0<\/em>&#8211; Rompope<\/li>\n<li><em>Fruitcake<\/em>\u00a0&#8211; Pastel de frutas<\/li>\n<li><em>Gingerbread<\/em>\u00a0&#8211; Pan de jengibre<\/li>\n<li><em>Gingerbread house<\/em>\u00a0&#8211; Casa de pan de jengibre<\/li>\n<li><em>Gingerbread man\u00a0<\/em>&#8211; mu\u00f1eco de pan de jengibre<\/li>\n<li><em>Hot chocolate<\/em>\u00a0&#8211; Chocolate caliente<\/li>\n<li><em>King Prawns<\/em>\u00a0&#8211; Langostinos<\/li>\n<li><em>Marzipan<\/em>\u00a0&#8211; Mazap\u00e1n<\/li>\n<li>Mince pies &#8211;\u00a0Especie de empanadillas de manzana<\/li>\n<li><em>Polvorones<\/em>\u00a0&#8211; Polvorones<\/li>\n<li>Roast potatoes &#8211; Patatas al horno con mantequilla<\/li>\n<li><em>Turkey<\/em>\u00a0&#8211; Pavo<\/li>\n<li><em>Turron<\/em>\u00a0&#8211; Turr\u00f3n<\/li>\n<\/ul>\n<h3>Tiempo t\u00edpico navide\u00f1o en ingl\u00e9s<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1583 size-full\" title=\"vocabulario tiempo navidad ingles\" src=\"https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2019\/12\/vocabulario-tiempo-navidad-ingles.jpg\" alt=\"\" width=\"626\" height=\"271\" \/><\/p>\n<ul>\n<li><em>Frosty\u00a0<\/em>&#8211; Escarchado<\/li>\n<li><em>Ice<\/em>\u00a0&#8211; Hielo<\/li>\n<li><em>Snow<\/em>\u00a0&#8211; Nieve<\/li>\n<li><em>Snowball<\/em>\u00a0&#8211; Bola de nieve<\/li>\n<li><em>Snowfall<\/em>\u00a0&#8211; Una nevada<\/li>\n<li><em>Snowflake\u00a0<\/em>&#8211; Copo de nieve<\/li>\n<li><em>Snowman<\/em>\u00a0&#8211; Hombre de nieve<\/li>\n<li><em>Snowy<\/em>\u00a0&#8211; Nevado<\/li>\n<li><em>Winter<\/em>\u00a0&#8211; Invierno<\/li>\n<\/ul>\n<div id=\"2\" class=\"content-list-title\">\n<div class=\"content-list-text numbered-text\">\n<div class=\"heading-wrapper\">\n<h3 class=\"heading\">Personajes de navidad en ingl\u00e9s<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content-list-body\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1585 size-full\" title=\"Personajes de navidad en ingl\u00e9s\" src=\"https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2019\/12\/personaje-navidad-en-ingles-vocabulario.jpg\" alt=\"\" width=\"626\" height=\"271\" \/><\/div>\n<div>\u00a0<\/div>\n<ul>\n<li><em>Angels<\/em>\u00a0&#8211; \u00c1ngeles<\/li>\n<li><em>Baby Jesus<\/em>\u00a0&#8211; El ni\u00f1o Jes\u00fas<\/li>\n<li><em>Elf<\/em>\u00a0&#8211; Duende<\/li>\n<li><em>Elves<\/em>\u00a0&#8211; Duendes.<\/li>\n<li><em>Family\u00a0<\/em>&#8211; Familia<\/li>\n<li><em>Frosty the Snowman<\/em>\u00a0&#8211; Frosty el hombre de nieve. Protagonista de una canci\u00f3n popular navide\u00f1a.<\/li>\n<li><em>Grinch<\/em>\u00a0&#8211; El Grinch. Personaje navide\u00f1o creado por\u00a0Dr.<strong>\u00a0<\/strong>Seuss<\/li>\n<li><em>Guest\u00a0<\/em>&#8211; Invitado<\/li>\n<li><em>Jack Frost<\/em>\u00a0&#8211; Padre Invierno<\/li>\n<li><em>Jesus<\/em>\u00a0&#8211; Jes\u00fas<\/li>\n<li><em>Joseph<\/em>\u00a0&#8211; Jos\u00e9<\/li>\n<li><em>Nutcracker<\/em>\u00a0&#8211; Cazcanueces<\/li>\n<li><em>Rudolph<\/em>\u00a0&#8211; Rudolph el reno<\/li>\n<li><em>Saint<\/em>\u00a0\u2013 Un santo<\/li>\n<li><em>Santa\u2019s helpers<\/em>\u00a0&#8211; Ayudantes de Santa Claus<\/li>\n<li><em>Santa Claus<\/em>\u00a0&#8211; Santa Claus<\/li>\n<li><em>Santa\u2019s workshop<\/em>\u00a0&#8211; Taller de Santa Claus<\/li>\n<li><em>Scrooge<\/em>\u00a0&#8211;\u00a0Scrooge. Protagonista de la novela Cuento de Navidad de Charles Dickens.<\/li>\n<li><em>Shepherds<\/em>\u00a0&#8211; Pastores<\/li>\n<li><em>The Christmas Spirit<\/em>\u00a0&#8211; El Esp\u00edritu Navide\u00f1o<\/li>\n<li><em>Three Kings\/Three Wise Men<\/em>\u00a0&#8211; Los Tres Reyes Magos<\/li>\n<li><em>Virgin Mary<\/em>\u00a0&#8211; La Virgen Mar\u00eda<\/li>\n<\/ul>\n<h3>Adornos navide\u00f1os en ingl\u00e9s<\/h3>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1582 size-full\" title=\"Adornos navide\u00f1os en ingl\u00e9s\" src=\"https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2019\/12\/adornos-de-navidad-en-ingles.jpg\" alt=\"\" width=\"626\" height=\"271\" \/><\/em><\/p>\n<ul>\n<li><em>Bells<\/em>\u00a0 &#8211; Campanas<\/li>\n<li><em>Candle\u00a0<\/em>&#8211; Vela<\/li>\n<li>Crib &#8211; Pesebre<\/li>\n<li><em>Christmas tree<\/em>\u00a0&#8211; \u00c1rbol de Navidad<\/li>\n<li><em>Decorations<\/em>\u00a0&#8211; Adornos<\/li>\n<li><em>Garland<\/em>\u00a0&#8211; Guirnalda<\/li>\n<li><em>Lights<\/em>\u00a0&#8211; Luces<\/li>\n<li><em>Nativity scene\u00a0<\/em>&#8211; Un bel\u00e9n<\/li>\n<li><em>Ornament<\/em>\u00a0&#8211; Objeto de decoraci\u00f3n<\/li>\n<li>Poinsettia &#8211; Flor de navidad<\/li>\n<li><em>Ribbon<\/em>\u00a0&#8211; List\u00f3n<\/li>\n<li>Tinsel &#8211; Espumill\u00f3n<\/li>\n<\/ul>\n<h3>Ropa t\u00edpica de navidad en ingl\u00e9s<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1586 size-full\" title=\"Ropa t\u00edpica de navidad en ingl\u00e9s\" src=\"https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2019\/12\/vocabulario-ropa-navidad-ingles.jpg\" alt=\"\" width=\"626\" height=\"271\" \/><\/p>\n<ul>\n<li><em>Boots<\/em>\u00a0&#8211; Botas<\/li>\n<li><em>Ice skates\u00a0<\/em>&#8211; Patines de hielo<\/li>\n<li><em>Gloves<\/em>\u00a0&#8211; Guantes<\/li>\n<li><em>Jacket<\/em>\u00a0&#8211; Chamarra\/Chaqueta<\/li>\n<li><em>Mittens\u00a0<\/em>&#8211; Mitones<\/li>\n<li><em>Scarf\u00a0<\/em>&#8211; Bufanda<\/li>\n<li><em>Socks<\/em>\u00a0&#8211; Calcetines<\/li>\n<li><em>Stockings<\/em>\u00a0&#8211; Calcetas<\/li>\n<li><em>Sweater<\/em>\u00a0&#8211; Su\u00e9ter<\/li>\n<\/ul>\n<h3>Otras palabras t\u00edpicas de navidad en ingl\u00e9s<\/h3>\n<ul>\n<li><em>Sleigh<\/em>\u00a0&#8211; Trineo<\/li>\n<li><em>North Pole<\/em>\u00a0&#8211; El Polo Norte<\/li>\n<li><em>Chimney<\/em>\u00a0&#8211; Chimenea<\/li>\n<li><em>Frankincense\u00a0<\/em>&#8211; Incienso<\/li>\n<li><em>Gold<\/em>\u00a0&#8211; Oro<\/li>\n<li><em>Myrrh<\/em>\u00a0&#8211; Mirra<\/li>\n<li><em>Mistletoe<\/em>\u00a0&#8211; Mu\u00e9rdago<\/li>\n<li><em>Pageant<\/em>\u00a0&#8211; Desfile<\/li>\n<li><em>Parade<\/em>\u00a0&#8211; Desfile<\/li>\n<li><em>Party\u00a0<\/em>&#8211; Fiesta<\/li>\n<li><em>Ritual<\/em>\u00a0&#8211; Ritual<\/li>\n<li><em>Christmas card<\/em>\u00a0&#8211;\u00a0Tarjeta de Navidad<\/li>\n<li><em>Happy New Year!<\/em>\u00a0&#8211; \u00a1Feliz A\u00f1o Nuevo!<\/li>\n<li><em>Hug<\/em>\u00a0&#8211; Abrazo<\/li>\n<li><em>Joy\u00a0<\/em>&#8211; Alegr\u00eda<\/li>\n<li><em>Love\u00a0<\/em>&#8211; Amor<\/li>\n<li><em>Holidays<\/em>\u00a0&#8211; Vacaciones<\/li>\n<li><em>New Year\u2019s Day<\/em>\u00a0&#8211; D\u00eda de a\u00f1o nuevo<\/li>\n<li><em>New Year\u2019s Eve<\/em>\u00a0&#8211; Nochevieja<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1844 size-full aligncenter\" src=\"https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/frases-navidad-ingles.png\" alt=\"vocabulario ingles espa\u00f1ol\" width=\"800\" height=\"800\" srcset=\"https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/frases-navidad-ingles.png 800w, https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/frases-navidad-ingles-768x768.png 768w, https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/frases-navidad-ingles-560x560.png 560w, https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/frases-navidad-ingles-367x367.png 367w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Y ya sabes, aprender el vocabulario de navidad en ingl\u00e9s m\u00e1s com\u00fan estos d\u00edas es esencial para disfrutar de las vacaciones en los pa\u00edses donde el ingl\u00e9s es el idioma oficial.<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Like Christmas came early!!! ? \u00a0 \u00a0 Las luces de navidad ya est\u00e1n encendidas en las calles y muchas personas deciden adornar sus casas en este puente de diciembre para empezar a celebrar esta navidad at\u00edpica. \u00a0 Por eso hoy os traemos como reto para este puente algunas de las palabras que m\u00e1s se utilizar\u00e1n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1838,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[8,11],"tags":[20],"class_list":["post-1577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ingles","category-vocabulario","tag-vocabulario"],"featured_image_src":{"landsacpe":["https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/vocabulario-de-navidad-en-ingles-1140x445.jpg",1140,445,true],"list":["https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/vocabulario-de-navidad-en-ingles-463x348.jpg",463,348,true],"medium":["https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/vocabulario-de-navidad-en-ingles-300x150.jpg",300,150,true],"full":["https:\/\/icedusolutions.com\/noticias\/wp-content\/uploads\/2020\/12\/vocabulario-de-navidad-en-ingles.jpg",2000,1000,false]},"_links":{"self":[{"href":"https:\/\/icedusolutions.com\/noticias\/wp-json\/wp\/v2\/posts\/1577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icedusolutions.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/icedusolutions.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/icedusolutions.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/icedusolutions.com\/noticias\/wp-json\/wp\/v2\/comments?post=1577"}],"version-history":[{"count":8,"href":"https:\/\/icedusolutions.com\/noticias\/wp-json\/wp\/v2\/posts\/1577\/revisions"}],"predecessor-version":[{"id":1852,"href":"https:\/\/icedusolutions.com\/noticias\/wp-json\/wp\/v2\/posts\/1577\/revisions\/1852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/icedusolutions.com\/noticias\/wp-json\/wp\/v2\/media\/1838"}],"wp:attachment":[{"href":"https:\/\/icedusolutions.com\/noticias\/wp-json\/wp\/v2\/media?parent=1577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/icedusolutions.com\/noticias\/wp-json\/wp\/v2\/categories?post=1577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/icedusolutions.com\/noticias\/wp-json\/wp\/v2\/tags?post=1577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}